{"id":9448,"count":3,"description":"","link":"https:\/\/ruse.news\/index.php\/post_tag\/osavremenyavane\/","name":"\u043e\u0441\u044a\u0432\u0440\u0435\u043c\u0435\u043d\u044f\u0432\u0430\u043d\u0435","slug":"osavremenyavane","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u043e\u0441\u044a\u0432\u0440\u0435\u043c\u0435\u043d\u044f\u0432\u0430\u043d\u0435 \u0410\u0440\u0445\u0438\u0432\u0438 - Ruse news - \u041d\u043e\u0432\u0438\u043d\u0438 \u043e\u0442 \u0420\u0443\u0441\u0435 \u0438 \u0440\u0435\u0433\u0438\u043e\u043d\u0430<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"bg_BG\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u043e\u0441\u044a\u0432\u0440\u0435\u043c\u0435\u043d\u044f\u0432\u0430\u043d\u0435 \u0410\u0440\u0445\u0438\u0432\u0438 - Ruse news - \u041d\u043e\u0432\u0438\u043d\u0438 \u043e\u0442 \u0420\u0443\u0441\u0435 \u0438 \u0440\u0435\u0433\u0438\u043e\u043d\u0430\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ruse.news\/index.php\/post_tag\/osavremenyavane\/\" \/>\n<meta property=\"og:site_name\" content=\"Ruse news - \u041d\u043e\u0432\u0438\u043d\u0438 \u043e\u0442 \u0420\u0443\u0441\u0435 \u0438 \u0440\u0435\u0433\u0438\u043e\u043d\u0430\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/ruse.news\\\/index.php\\\/post_tag\\\/osavremenyavane\\\/\",\"url\":\"https:\\\/\\\/ruse.news\\\/index.php\\\/post_tag\\\/osavremenyavane\\\/\",\"name\":\"\u043e\u0441\u044a\u0432\u0440\u0435\u043c\u0435\u043d\u044f\u0432\u0430\u043d\u0435 \u0410\u0440\u0445\u0438\u0432\u0438 - Ruse news - \u041d\u043e\u0432\u0438\u043d\u0438 \u043e\u0442 \u0420\u0443\u0441\u0435 \u0438 \u0440\u0435\u0433\u0438\u043e\u043d\u0430\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ruse.news\\\/#website\"},\"inLanguage\":\"bg-BG\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ruse.news\\\/#website\",\"url\":\"https:\\\/\\\/ruse.news\\\/\",\"name\":\"Ruse news - \u041d\u043e\u0432\u0438\u043d\u0438 \u043e\u0442 \u0420\u0443\u0441\u0435 \u0438 \u0440\u0435\u0433\u0438\u043e\u043d\u0430\",\"description\":\"\u041d\u043e\u0432\u0438\u043d\u0438 \u043e\u0442 \u0420\u0443\u0441\u0435 \u0438 \u0440\u0435\u0433\u0438\u043e\u043d\u0430\",\"publisher\":{\"@id\":\"https:\\\/\\\/ruse.news\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ruse.news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"bg-BG\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ruse.news\\\/#organization\",\"name\":\"Ruse news - \u041d\u043e\u0432\u0438\u043d\u0438 \u043e\u0442 \u0420\u0443\u0441\u0435 \u0438 \u0440\u0435\u0433\u0438\u043e\u043d\u0430\",\"url\":\"https:\\\/\\\/ruse.news\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"bg-BG\",\"@id\":\"https:\\\/\\\/ruse.news\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ruse.news\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/rnewswhitestroke-2.png\",\"contentUrl\":\"https:\\\/\\\/ruse.news\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/rnewswhitestroke-2.png\",\"width\":4043,\"height\":1819,\"caption\":\"Ruse news - \u041d\u043e\u0432\u0438\u043d\u0438 \u043e\u0442 \u0420\u0443\u0441\u0435 \u0438 \u0440\u0435\u0433\u0438\u043e\u043d\u0430\"},\"image\":{\"@id\":\"https:\\\/\\\/ruse.news\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/www.ruse.news\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u043e\u0441\u044a\u0432\u0440\u0435\u043c\u0435\u043d\u044f\u0432\u0430\u043d\u0435 \u0410\u0440\u0445\u0438\u0432\u0438 - Ruse news - \u041d\u043e\u0432\u0438\u043d\u0438 \u043e\u0442 \u0420\u0443\u0441\u0435 \u0438 \u0440\u0435\u0433\u0438\u043e\u043d\u0430","robots":{"index":"noindex","follow":"follow"},"og_locale":"bg_BG","og_type":"article","og_title":"\u043e\u0441\u044a\u0432\u0440\u0435\u043c\u0435\u043d\u044f\u0432\u0430\u043d\u0435 \u0410\u0440\u0445\u0438\u0432\u0438 - Ruse news - \u041d\u043e\u0432\u0438\u043d\u0438 \u043e\u0442 \u0420\u0443\u0441\u0435 \u0438 \u0440\u0435\u0433\u0438\u043e\u043d\u0430","og_url":"https:\/\/ruse.news\/index.php\/post_tag\/osavremenyavane\/","og_site_name":"Ruse news - \u041d\u043e\u0432\u0438\u043d\u0438 \u043e\u0442 \u0420\u0443\u0441\u0435 \u0438 \u0440\u0435\u0433\u0438\u043e\u043d\u0430","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/ruse.news\/index.php\/post_tag\/osavremenyavane\/","url":"https:\/\/ruse.news\/index.php\/post_tag\/osavremenyavane\/","name":"\u043e\u0441\u044a\u0432\u0440\u0435\u043c\u0435\u043d\u044f\u0432\u0430\u043d\u0435 \u0410\u0440\u0445\u0438\u0432\u0438 - Ruse news - \u041d\u043e\u0432\u0438\u043d\u0438 \u043e\u0442 \u0420\u0443\u0441\u0435 \u0438 \u0440\u0435\u0433\u0438\u043e\u043d\u0430","isPartOf":{"@id":"https:\/\/ruse.news\/#website"},"inLanguage":"bg-BG"},{"@type":"WebSite","@id":"https:\/\/ruse.news\/#website","url":"https:\/\/ruse.news\/","name":"Ruse news - \u041d\u043e\u0432\u0438\u043d\u0438 \u043e\u0442 \u0420\u0443\u0441\u0435 \u0438 \u0440\u0435\u0433\u0438\u043e\u043d\u0430","description":"\u041d\u043e\u0432\u0438\u043d\u0438 \u043e\u0442 \u0420\u0443\u0441\u0435 \u0438 \u0440\u0435\u0433\u0438\u043e\u043d\u0430","publisher":{"@id":"https:\/\/ruse.news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ruse.news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"bg-BG"},{"@type":"Organization","@id":"https:\/\/ruse.news\/#organization","name":"Ruse news - \u041d\u043e\u0432\u0438\u043d\u0438 \u043e\u0442 \u0420\u0443\u0441\u0435 \u0438 \u0440\u0435\u0433\u0438\u043e\u043d\u0430","url":"https:\/\/ruse.news\/","logo":{"@type":"ImageObject","inLanguage":"bg-BG","@id":"https:\/\/ruse.news\/#\/schema\/logo\/image\/","url":"https:\/\/ruse.news\/wp-content\/uploads\/2021\/06\/rnewswhitestroke-2.png","contentUrl":"https:\/\/ruse.news\/wp-content\/uploads\/2021\/06\/rnewswhitestroke-2.png","width":4043,"height":1819,"caption":"Ruse news - \u041d\u043e\u0432\u0438\u043d\u0438 \u043e\u0442 \u0420\u0443\u0441\u0435 \u0438 \u0440\u0435\u0433\u0438\u043e\u043d\u0430"},"image":{"@id":"https:\/\/ruse.news\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/www.ruse.news"]}]}},"_links":{"self":[{"href":"https:\/\/ruse.news\/index.php\/wp-json\/wp\/v2\/tags\/9448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ruse.news\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ruse.news\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ruse.news\/index.php\/wp-json\/wp\/v2\/posts?tags=9448"},{"href":"https:\/\/ruse.news\/index.php\/wp-json\/wp\/v2\/ajde_events?tags=9448"},{"href":"https:\/\/ruse.news\/index.php\/wp-json\/wp\/v2\/tribe_events?tags=9448"},{"href":"https:\/\/ruse.news\/index.php\/wp-json\/wp\/v2\/tec_calendar_embed?tags=9448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}